{"id":15823,"date":"2018-04-16T09:02:52","date_gmt":"2018-04-16T07:02:52","guid":{"rendered":"https:\/\/svhermersberg.de\/wp\/2018\/04\/16\/svh-ue40-steht-im-kreispokalfinale\/"},"modified":"2018-04-16T09:02:52","modified_gmt":"2018-04-16T07:02:52","slug":"svh-ue40-steht-im-kreispokalfinale","status":"publish","type":"post","link":"https:\/\/svhermersberg.de\/wp\/2018\/04\/16\/svh-ue40-steht-im-kreispokalfinale\/","title":{"rendered":"SVH \u00dc40 steht im Kreispokalfinale"},"content":{"rendered":"<p>Im Elfmeterschie\u00dfen setzte sich unsere \u00dc40 Mannschaft im Halbfinale gegen Leimen durch und steht somit im Finale. Nach einem gravierenden Abwehrfehler stand es \u00fcberraschend 0:1 f\u00fcr Leimen. In der Folge war der SVH sehr bem\u00fcht das Spiel zu kontrollieren und zu gestalten. Trotz mannschaftlicher \u00dcberlegenheit gelang zun\u00e4chst aber nicht der Ausgleichstreffer und Leimen blieb mit seinen schnellen St\u00fcrmern stehts gef\u00e4hrlich. Erst Mitte der 2. Halbzeit wurde das Hermersberg Bem\u00fchen belohnt: Nach einer sch\u00f6nen Flanke konnte Marc Smith halb im Flug per Kopf den Ausgleich erzielen. Von da an dr\u00e4ngte der SVH auf den Siegtreffer. Beste Gelegenheiten durch Fuchs oder Reichert blieben aber ungenutzt.&nbsp;<\/p>\n<p>Nach dem Ende der regul\u00e4ren Spielzeit stand es also 1:1. Im Elfmeterschie\u00dfen musste der Sieger ermittelt werden. Beim SVH traf jeder Spieler souver\u00e4n. Unser Ausweichtorwart (und eigentlich Feldspieler) Thomas Fuchs parierte 2 Elmeter von Leimen und sichert so den Einzug ins Finale.<\/p>\n<p>Das Finale gegen den SV Hochstellerhof findet am 28.04. beim SV Hochstellerhof statt.&nbsp;<\/p>\n<p>RKO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Elfmeterschie\u00dfen setzte sich unsere \u00dc40 Mannschaft im Halbfinale gegen Leimen durch und steht somit im Finale. Nach einem gravierenden Abwehrfehler stand es \u00fcberraschend 0:1 f\u00fcr Leimen. In der Folge war der SVH sehr bem\u00fcht das Spiel zu kontrollieren und zu gestalten. Trotz mannschaftlicher \u00dcberlegenheit gelang zun\u00e4chst aber nicht der Ausgleichstreffer und Leimen blieb mit<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[106],"tags":[],"class_list":["post-15823","post","type-post","status-publish","format-standard","hentry","category-ah-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/posts\/15823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/comments?post=15823"}],"version-history":[{"count":0,"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/posts\/15823\/revisions"}],"wp:attachment":[{"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/media?parent=15823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/categories?post=15823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svhermersberg.de\/wp\/wp-json\/wp\/v2\/tags?post=15823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}